{"id":200141,"date":"2026-03-30T13:41:12","date_gmt":"2026-03-30T17:41:12","guid":{"rendered":"https:\/\/unstamps.org\/?post_type=product&#038;p=200141"},"modified":"2026-07-09T13:00:19","modified_gmt":"2026-07-09T17:00:19","slug":"dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge","status":"publish","type":"product","link":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/","title":{"rendered":"D\u00eda Internacional de Los Bosques &#8211; Sobre de primer d\u00eda Single GE"},"content":{"rendered":"<p><em>(El sobre de primer d\u00eda de la imagen es una muestra; los originales pueden ser ligeramente diferentes).<\/em><\/p>\n<p>Los sobres de primer d\u00eda de los sellos relativos al \u00abD\u00eda Internacional de Los Bosques\u00bb se emitir\u00e1n en las siguientes versiones:<\/p>\n<ul>\n<li><strong>Individual:<\/strong> un total de tres sobres con sendos sellos, debidamente matasellados, de cada uno de los valores faciales emitidos<\/li>\n<li><strong>Bloque con inscripciones marginales:<\/strong> un total de tres sobres, cada uno con un bloque de cuatro sellos con inscripciones marginales de los valores faciales emitidos, debidamente matasellados<\/li>\n<li><strong>Triple:<\/strong> un sobre de gran formato con los tres sellos de las Naciones Unidas debidamente matasellados por las Oficinas de Nueva York, Ginebra y Viena<\/li>\n<\/ul>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-200195\" src=\"https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-Cancels-web-860x314.jpg\" alt=\"\" width=\"860\" height=\"314\" srcset=\"https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-Cancels-web-860x314.jpg 860w, https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-Cancels-web-768x280.jpg 768w, https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-Cancels-web-1170x427.jpg 1170w, https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-Cancels-web-600x219.jpg 600w, https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-Cancels-web.jpg 1200w\" sizes=\"auto, (max-width: 860px) 100vw, 860px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>(El sobre de primer d\u00eda de la imagen es una muestra; los originales pueden ser ligeramente diferentes). Los sobres de primer d\u00eda de los sellos relativos al \u00abD\u00eda Internacional de Los Bosques\u00bb se emitir\u00e1n en las siguientes versiones: Individual: un total de tres sobres con sendos sellos, debidamente matasellados, de cada uno de los valores [&hellip;]<\/p>\n","protected":false},"featured_media":200259,"comment_status":"closed","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"product_brand":[],"product_cat":[2964,926,940],"product_tag":[],"class_list":["post-200141","product","type-product","status-publish","has-post-thumbnail","product_cat-2026-es","product_cat-ginebra","product_cat-sobres-de-primer-dia-de-emision","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00eda Internacional de Los Bosques - Sobre de primer d\u00eda Single GE - UN Stamps<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00eda Internacional de Los Bosques - Sobre de primer d\u00eda Single GE - UN Stamps\" \/>\n<meta property=\"og:description\" content=\"(El sobre de primer d\u00eda de la imagen es una muestra; los originales pueden ser ligeramente diferentes). Los sobres de primer d\u00eda de los sellos relativos al \u00abD\u00eda Internacional de Los Bosques\u00bb se emitir\u00e1n en las siguientes versiones: Individual: un total de tres sobres con sendos sellos, debidamente matasellados, de cada uno de los valores [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/\" \/>\n<meta property=\"og:site_name\" content=\"UN Stamps\" \/>\n<meta property=\"article:modified_time\" content=\"2026-07-09T17:00:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-FDC-Single-GE.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/\",\"url\":\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/\",\"name\":\"D\u00eda Internacional de Los Bosques - Sobre de primer d\u00eda Single GE - UN Stamps\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/2026-Forests-FDC-Single-GE.jpg\",\"datePublished\":\"2026-03-30T17:41:12+00:00\",\"dateModified\":\"2026-07-09T17:00:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/2026-Forests-FDC-Single-GE.jpg\",\"contentUrl\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/2026-Forests-FDC-Single-GE.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/producto\\\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/unstamps.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/unstamps.org\\\/es\\\/productos\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"D\u00eda Internacional de Los Bosques &#8211; Sobre de primer d\u00eda Single GE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/unstamps.org\\\/es\\\/\",\"name\":\"UN Stamps\",\"description\":\"United Nations Stamps\",\"publisher\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unstamps.org\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/#organization\",\"name\":\"UN Stamps\",\"url\":\"https:\\\/\\\/unstamps.org\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/logo4web.jpg\",\"contentUrl\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/logo4web.jpg\",\"width\":2500,\"height\":250,\"caption\":\"UN Stamps\"},\"image\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00eda Internacional de Los Bosques - Sobre de primer d\u00eda Single GE - UN Stamps","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/","og_locale":"es_ES","og_type":"article","og_title":"D\u00eda Internacional de Los Bosques - Sobre de primer d\u00eda Single GE - UN Stamps","og_description":"(El sobre de primer d\u00eda de la imagen es una muestra; los originales pueden ser ligeramente diferentes). Los sobres de primer d\u00eda de los sellos relativos al \u00abD\u00eda Internacional de Los Bosques\u00bb se emitir\u00e1n en las siguientes versiones: Individual: un total de tres sobres con sendos sellos, debidamente matasellados, de cada uno de los valores [&hellip;]","og_url":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/","og_site_name":"UN Stamps","article_modified_time":"2026-07-09T17:00:19+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-FDC-Single-GE.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/","url":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/","name":"D\u00eda Internacional de Los Bosques - Sobre de primer d\u00eda Single GE - UN Stamps","isPartOf":{"@id":"https:\/\/unstamps.org\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/#primaryimage"},"image":{"@id":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/#primaryimage"},"thumbnailUrl":"https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-FDC-Single-GE.jpg","datePublished":"2026-03-30T17:41:12+00:00","dateModified":"2026-07-09T17:00:19+00:00","breadcrumb":{"@id":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/#primaryimage","url":"https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-FDC-Single-GE.jpg","contentUrl":"https:\/\/unstamps.org\/wp-content\/uploads\/2026\/03\/2026-Forests-FDC-Single-GE.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/unstamps.org\/es\/producto\/dia-internacional-de-los-bosques-sobre-de-primer-dia-single-ge\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/unstamps.org\/es\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/unstamps.org\/es\/productos\/"},{"@type":"ListItem","position":3,"name":"D\u00eda Internacional de Los Bosques &#8211; Sobre de primer d\u00eda Single GE"}]},{"@type":"WebSite","@id":"https:\/\/unstamps.org\/es\/#website","url":"https:\/\/unstamps.org\/es\/","name":"UN Stamps","description":"United Nations Stamps","publisher":{"@id":"https:\/\/unstamps.org\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unstamps.org\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/unstamps.org\/es\/#organization","name":"UN Stamps","url":"https:\/\/unstamps.org\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/unstamps.org\/es\/#\/schema\/logo\/image\/","url":"https:\/\/unstamps.org\/wp-content\/uploads\/2014\/01\/logo4web.jpg","contentUrl":"https:\/\/unstamps.org\/wp-content\/uploads\/2014\/01\/logo4web.jpg","width":2500,"height":250,"caption":"UN Stamps"},"image":{"@id":"https:\/\/unstamps.org\/es\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:05:07","action":"change-status","newStatus":"private","terms":[],"taxonomy":"product_cat","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/product\/200141","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/comments?post=200141"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/media\/200259"}],"wp:attachment":[{"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/media?parent=200141"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/product_brand?post=200141"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/product_cat?post=200141"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/unstamps.org\/es\/wp-json\/wp\/v2\/product_tag?post=200141"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}