{"id":885,"count":1,"description":"","link":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/","name":"Event Bogen","slug":"event-sheet-de","taxonomy":"product_cat","parent":158,"meta":[],"menu_order":17,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Event Bogen Archives - UN Briefmarken<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Event Bogen Archives - UN Briefmarken\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/\" \/>\n<meta property=\"og:site_name\" content=\"UN Briefmarken\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt-kategorie\\\/produkte\\\/event-sheet-de\\\/\",\"url\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt-kategorie\\\/produkte\\\/event-sheet-de\\\/\",\"name\":\"Event Bogen Archives - UN Briefmarken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt-kategorie\\\/produkte\\\/event-sheet-de\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt-kategorie\\\/produkte\\\/event-sheet-de\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/unstamps.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt-kategorie\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Event Bogen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/unstamps.org\\\/de\\\/\",\"name\":\"UN Stamps\",\"description\":\"United Nations Stamps\",\"publisher\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unstamps.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#organization\",\"name\":\"UN Stamps\",\"url\":\"https:\\\/\\\/unstamps.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/logo4web.jpg\",\"contentUrl\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/logo4web.jpg\",\"width\":2500,\"height\":250,\"caption\":\"UN Stamps\"},\"image\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Event Bogen Archives - UN Briefmarken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/","og_locale":"de_DE","og_type":"article","og_title":"Event Bogen Archives - UN Briefmarken","og_url":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/","og_site_name":"UN Briefmarken","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/","url":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/","name":"Event Bogen Archives - UN Briefmarken","isPartOf":{"@id":"https:\/\/unstamps.org\/de\/#website"},"breadcrumb":{"@id":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/#breadcrumb"},"inLanguage":"de-DE"},{"@type":"BreadcrumbList","@id":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/event-sheet-de\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/unstamps.org\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/unstamps.org\/de\/produkt-kategorie\/produkte\/"},{"@type":"ListItem","position":3,"name":"Event Bogen"}]},{"@type":"WebSite","@id":"https:\/\/unstamps.org\/de\/#website","url":"https:\/\/unstamps.org\/de\/","name":"UN Stamps","description":"United Nations Stamps","publisher":{"@id":"https:\/\/unstamps.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unstamps.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/unstamps.org\/de\/#organization","name":"UN Stamps","url":"https:\/\/unstamps.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/unstamps.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/unstamps.org\/wp-content\/uploads\/2014\/01\/logo4web.jpg","contentUrl":"https:\/\/unstamps.org\/wp-content\/uploads\/2014\/01\/logo4web.jpg","width":2500,"height":250,"caption":"UN Stamps"},"image":{"@id":"https:\/\/unstamps.org\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product_cat\/885","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product_cat\/158"}],"wp:post_type":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product?product_cat=885"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}