{"id":1013,"date":"2013-12-12T05:06:00","date_gmt":"2013-12-12T10:08:40","guid":{"rendered":"http:\/\/unstamps.org\/?post_type=product&#038;p=1013"},"modified":"2024-01-26T10:00:00","modified_gmt":"2024-01-26T15:00:00","slug":"1996-genf-f-s-040-einzelmarke-gestempelt","status":"publish","type":"product","link":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/","title":{"rendered":"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt"},"content":{"rendered":"<p>&#8220;Galoppierendes Pferd&#8221; &#8211; Nach dem Photo einer chinesischen Bronzeskulptur der \u00d6stlichen Han Dynastie (25-220 v. Chr.) von Laurent Bianco (Schweiz), mit dem Titel &#8220;Galoppierendes Pferd auf eine Fliegende Schwalbe tretend&#8221;.<\/p>\n<div id=\"prod-descr-denomination\">\n<div>Nennwert:<\/div>\n<p>CHF 0,40 (Bogen zu 50 Marken)<\/p>\n<\/div>\n<div id=\"prod-descr-printing\">\n<div>Druck:<\/div>\n<p>Offset Lithographie von The House of Questa (Vereinigtes K\u00f6nigreich)<\/p>\n<\/div>\n<div id=\"prod-descr-quantity\">\n<div>Auflage:<\/div>\n<p>1.125.000 Briefmarken<\/p>\n<\/div>\n<div id=\"prod-descr-designer\">\n<div>Designer:<\/div>\n<p>von Rocco Callari (Vereinte Nationen, New York) als Briefmarke adaptiert<\/p>\n<\/div>\n<div id=\"prod-descr-specification\">\n<div>Spezifikation:<\/div>\n<p>35,96 mm x 25,73 mm; Z\u00e4hnung: 14<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Galoppierendes Pferd&#8221; &#8211; Nach dem Photo einer chinesischen Bronzeskulptur der \u00d6stlichen Han Dynastie (25-220 v. Chr.) von Laurent Bianco (Schweiz), mit dem Titel &#8220;Galoppierendes Pferd auf eine Fliegende Schwalbe tretend&#8221;. Nennwert: CHF 0,40 (Bogen zu 50 Marken) Druck: Offset Lithographie von The House of Questa (Vereinigtes K\u00f6nigreich) Auflage: 1.125.000 Briefmarken Designer: von Rocco Callari (Vereinte [&hellip;]<\/p>\n","protected":false},"featured_media":8025,"comment_status":"open","ping_status":"closed","template":"","meta":{"ngg_post_thumbnail":0},"product_brand":[],"product_cat":[971],"product_tag":[],"class_list":["post-1013","product","type-product","status-publish","has-post-thumbnail","product_cat-2019-year","first","instock","shipping-taxable","purchasable","product-type-simple"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt - UN Briefmarken<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt - UN Briefmarken\" \/>\n<meta property=\"og:description\" content=\"&#8220;Galoppierendes Pferd&#8221; &#8211; Nach dem Photo einer chinesischen Bronzeskulptur der \u00d6stlichen Han Dynastie (25-220 v. Chr.) von Laurent Bianco (Schweiz), mit dem Titel &#8220;Galoppierendes Pferd auf eine Fliegende Schwalbe tretend&#8221;. Nennwert: CHF 0,40 (Bogen zu 50 Marken) Druck: Offset Lithographie von The House of Questa (Vereinigtes K\u00f6nigreich) Auflage: 1.125.000 Briefmarken Designer: von Rocco Callari (Vereinte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/\" \/>\n<meta property=\"og:site_name\" content=\"UN Briefmarken\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-26T15:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/unstamps.org\/wp-content\/uploads\/2013\/12\/DEF-G-1996_fs0.40_single.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"1024\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/\",\"url\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/\",\"name\":\"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt - UN Briefmarken\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/DEF-G-1996_fs0.40_single.jpg\",\"datePublished\":\"2013-12-12T10:08:40+00:00\",\"dateModified\":\"2024-01-26T15:00:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/#primaryimage\",\"url\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/DEF-G-1996_fs0.40_single.jpg\",\"contentUrl\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2013\\\/12\\\/DEF-G-1996_fs0.40_single.jpg\",\"width\":1024,\"height\":1024},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkt\\\/1996-genf-f-s-040-einzelmarke-gestempelt\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/unstamps.org\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Produkte\",\"item\":\"https:\\\/\\\/unstamps.org\\\/de\\\/produkte\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/unstamps.org\\\/de\\\/\",\"name\":\"UN Stamps\",\"description\":\"United Nations Stamps\",\"publisher\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/unstamps.org\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#organization\",\"name\":\"UN Stamps\",\"url\":\"https:\\\/\\\/unstamps.org\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/logo4web.jpg\",\"contentUrl\":\"https:\\\/\\\/unstamps.org\\\/wp-content\\\/uploads\\\/2014\\\/01\\\/logo4web.jpg\",\"width\":2500,\"height\":250,\"caption\":\"UN Stamps\"},\"image\":{\"@id\":\"https:\\\/\\\/unstamps.org\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt - UN Briefmarken","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/","og_locale":"de_DE","og_type":"article","og_title":"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt - UN Briefmarken","og_description":"&#8220;Galoppierendes Pferd&#8221; &#8211; Nach dem Photo einer chinesischen Bronzeskulptur der \u00d6stlichen Han Dynastie (25-220 v. Chr.) von Laurent Bianco (Schweiz), mit dem Titel &#8220;Galoppierendes Pferd auf eine Fliegende Schwalbe tretend&#8221;. Nennwert: CHF 0,40 (Bogen zu 50 Marken) Druck: Offset Lithographie von The House of Questa (Vereinigtes K\u00f6nigreich) Auflage: 1.125.000 Briefmarken Designer: von Rocco Callari (Vereinte [&hellip;]","og_url":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/","og_site_name":"UN Briefmarken","article_modified_time":"2024-01-26T15:00:00+00:00","og_image":[{"width":1024,"height":1024,"url":"https:\/\/unstamps.org\/wp-content\/uploads\/2013\/12\/DEF-G-1996_fs0.40_single.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/","url":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/","name":"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt - UN Briefmarken","isPartOf":{"@id":"https:\/\/unstamps.org\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/#primaryimage"},"image":{"@id":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/#primaryimage"},"thumbnailUrl":"https:\/\/unstamps.org\/wp-content\/uploads\/2013\/12\/DEF-G-1996_fs0.40_single.jpg","datePublished":"2013-12-12T10:08:40+00:00","dateModified":"2024-01-26T15:00:00+00:00","breadcrumb":{"@id":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/"]}]},{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/#primaryimage","url":"https:\/\/unstamps.org\/wp-content\/uploads\/2013\/12\/DEF-G-1996_fs0.40_single.jpg","contentUrl":"https:\/\/unstamps.org\/wp-content\/uploads\/2013\/12\/DEF-G-1996_fs0.40_single.jpg","width":1024,"height":1024},{"@type":"BreadcrumbList","@id":"https:\/\/unstamps.org\/de\/produkt\/1996-genf-f-s-040-einzelmarke-gestempelt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/unstamps.org\/de\/"},{"@type":"ListItem","position":2,"name":"Produkte","item":"https:\/\/unstamps.org\/de\/produkte\/"},{"@type":"ListItem","position":3,"name":"1996 Genf F.s. 0,40 Einzelmarke &#8211; Gestempelt"}]},{"@type":"WebSite","@id":"https:\/\/unstamps.org\/de\/#website","url":"https:\/\/unstamps.org\/de\/","name":"UN Stamps","description":"United Nations Stamps","publisher":{"@id":"https:\/\/unstamps.org\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/unstamps.org\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Organization","@id":"https:\/\/unstamps.org\/de\/#organization","name":"UN Stamps","url":"https:\/\/unstamps.org\/de\/","logo":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/unstamps.org\/de\/#\/schema\/logo\/image\/","url":"https:\/\/unstamps.org\/wp-content\/uploads\/2014\/01\/logo4web.jpg","contentUrl":"https:\/\/unstamps.org\/wp-content\/uploads\/2014\/01\/logo4web.jpg","width":2500,"height":250,"caption":"UN Stamps"},"image":{"@id":"https:\/\/unstamps.org\/de\/#\/schema\/logo\/image\/"}}]}},"jetpack_sharing_enabled":true,"publishpress_future_action":{"enabled":false,"date":"2026-07-22 11:14:11","action":"change-status","newStatus":"private","terms":[],"taxonomy":"product_cat","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product\/1013","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/comments?post=1013"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/media\/8025"}],"wp:attachment":[{"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/media?parent=1013"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product_brand?post=1013"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product_cat?post=1013"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/unstamps.org\/de\/wp-json\/wp\/v2\/product_tag?post=1013"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}